{"id":21384,"date":"2024-07-24T10:40:06","date_gmt":"2024-07-24T10:40:06","guid":{"rendered":"https:\/\/mercurifashion.com\/?page_id=21384"},"modified":"2024-08-31T06:43:45","modified_gmt":"2024-08-31T06:43:45","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/mercurifashion.com\/it\/privacy-policy\/","title":{"rendered":"Informativa sulla Privacy"},"content":{"rendered":"<h1>Informativa sulla Privacy<\/h1>\n<p><strong>Informativa sulla Privacy di MERCURI S.R.L. per il sito web mercurifashion.com<\/strong><\/p>\n<p>Questa informativa sulla privacy (di seguito &#8220;Informativa sulla Privacy&#8221;) fornisce dettagli cruciali sulle informazioni personali che raccogliamo quando visiti il nostro sito web, mercurifashion.com, altri siti web relativi al marchio e pagine ufficiali dei social media (collettivamente denominati &#8220;Siti Web&#8221;), indipendentemente dal fatto che tu sia un utente registrato. Spiega anche come utilizziamo queste informazioni. Inoltre, questa Informativa sulla Privacy descrive come gestiamo le informazioni che potresti fornire o che raccogliamo su di te quando visiti le nostre boutique gestite direttamente da noi o dai nostri affiliati (&#8220;Boutique&#8221;), o punti vendita gestiti dai nostri partner commerciali (&#8220;Punti Vendita&#8221;), o durante qualsiasi altra interazione con noi. Questa informativa integra qualsiasi altra informazione che potresti aver ricevuto in quelle specifiche situazioni.<\/p>\n<p>Questo documento ti offre informazioni essenziali sui seguenti argomenti:<\/p>\n<ol>\n<li>TRATTAMENTO DEI DATI PERSONALI<\/li>\n<li>DATI PERSONALI CHE RACCOGLIAMO<\/li>\n<li>COME UTILIZZIAMO I DATI PERSONALI<\/li>\n<li>COME CONDIVIDIAMO I DATI PERSONALI<\/li>\n<li>PRIVACY DEI BAMBINI<\/li>\n<li>CONSERVAZIONE, ACCESSIBILIT\u00c0 E TRASFERIMENTO DEI DATI PERSONALI<\/li>\n<li>SICUREZZA E RISERVATEZZA DEI DATI PERSONALI<\/li>\n<li>DIRITTI RELATIVI AI DATI PERSONALI &#8211; GESTIONE DELLE TUE SCELTE<\/li>\n<li>DIRITTI DI PRIVACY DELLA CALIFORNIA<\/li>\n<li>CONSERVAZIONE DEI DATI<\/li>\n<li>LA NOSTRA POLITICA SUI COOKIE E TECNOLOGIE SIMILI<\/li>\n<li>LINK, INSERZIONISTI, SPONSOR E ANNUNCI PUBBLICITARI<\/li>\n<li>TITOLARE DEL TRATTAMENTO &#8211; RESPONSABILE DELLA PROTEZIONE DEI DATI &#8211; E COME CONTATTARCI<\/li>\n<li>AGGIORNAMENTO DI QUESTA POLITICA &#8211; AVVISI<\/li>\n<\/ol>\n<p><strong>ACCETTAZIONE<\/strong><\/p>\n<p>Accedendo al Sito Web, utilizzando i suoi servizi o interagendo con noi attraverso i nostri Punti Vendita, Boutique e\/o Siti Web, confermi di aver letto e compreso questa Informativa sulla Privacy e accetti che possiamo raccogliere, utilizzare, conservare, trasmettere e divulgare i dati personali che raccogliamo attraverso i Siti Web, Boutique e\/o Punti Vendita in conformit\u00e0 con questa Informativa sulla Privacy. Se non ti sei ancora registrato con noi, potremmo chiederti di opt-in (ad esempio, spuntando una casella) se lo riteniamo necessario per proteggere i tuoi diritti o come richiesto dalle leggi applicabili. Se non accetti i termini di questa Informativa sulla Privacy, ti preghiamo di astenerti dal visitare questo Sito Web, creare un account, utilizzare o inviare dati personali a questo Sito Web, o fare opt-in quando questa opzione \u00e8 presentata in conformit\u00e0 con le leggi applicabili.<\/p>\n<p><strong>1. TRATTAMENTO DEI DATI PERSONALI<\/strong><\/p>\n<p>In questa Informativa sulla Privacy, per &#8220;Dati Personali&#8221; si intende qualsiasi informazione che ci consenta di identificarti (o identificare una terza parte i cui dati personali ci fornisci) direttamente o indirettamente, inclusi i dettagli associati all&#8217;acquisto di beni o servizi, o qualsiasi informazione che scegli di comunicarci o condividere con noi o con terze parti mentre utilizzi i Siti Web o nei Punti Vendita. Tratteremo i dati personali in conformit\u00e0 con il Regolamento Generale sulla Protezione dei Dati (UE) 2016\/679 &#8220;Reg. (UE) 2016\/679&#8221; e le leggi del paese in cui i dati sono raccolti, se applicabile. Ci riserviamo il diritto di effettuare trattamenti aggiuntivi come richiesto dalla legge o nell&#8217;ambito di un&#8217;indagine o procedimento penale o altro procedimento legale.<\/p>\n<p><strong>2. DATI PERSONALI CHE RACCOGLIAMO<\/strong><\/p>\n<p><strong>2.1 Fonte dei Dati<\/strong><br \/>\nRaccogliamo dati personali da te solo quando ci fornisci volontariamente queste informazioni, come ad esempio:<\/p>\n<ul>\n<li><strong>Siti Web del marchio che distribuiscono i nostri prodotti<\/strong>: Quando effettui un ordine tramite il\/i Sito\/i Web come &#8220;ospite&#8221;; creando o modificando il tuo account; impostando una lista dei desideri; partecipando a un concorso, lotteria o promozione; effettuando ricerche sul Sito Web; contattandoci con un commento o una domanda; iscrivendoti alle newsletter via email e agli aggiornamenti riguardanti i nostri ultimi prodotti e servizi, aperture di boutique, eventi o promozioni; o richiedendo di ricevere una conferma d&#8217;ordine, conferma di spedizione o altri avvisi.<\/li>\n<li><strong>Le nostre Boutique e Punti Vendita<\/strong>: Quando compili la nostra scheda cliente, durante conversazioni informali quando visiti le nostre Boutique o Punti Vendita, interagisci con noi o acquisti merce.<\/li>\n<li><strong>Eventi<\/strong>: Quando partecipi ai nostri eventi, sondaggi, ricerche di mercato, sfide e altre promozioni, anche online, ad esempio mini-siti che gestiamo su reti sociali di terze parti come Facebook.<\/li>\n<li><strong>I nostri servizi clienti<\/strong>: Quando richiedi assistenza, servizi speciali o supporto post-vendita.<\/li>\n<li><strong>Email, SMS e altri messaggi elettronici<\/strong>: Durante le comunicazioni tra te e noi.<\/li>\n<\/ul>\n<p>Se ci fornisci informazioni personali di terzi (ad esempio, i tuoi familiari, altri clienti o potenziali clienti), devi assicurarti che questi terzi siano informati e abbiano autorizzato l&#8217;uso dei loro dati come descritto in questa Informativa sulla Privacy.<\/p>\n<p><strong>2.2 Tipi di Dati<\/strong><br \/>\nPotremmo raccogliere e utilizzare diversi tipi di dati personali a seconda dello scopo specifico, come descritto di seguito:<\/p>\n<ul>\n<li><strong>Dati personali<\/strong>: Come nome, cognome, genere, et\u00e0\/data di nascita, paese di origine e altri dettagli personali consentiti dalle leggi applicabili.<\/li>\n<li><strong>Dati di contatto<\/strong>: Come indirizzo, indirizzo email, numero di telefono, numero di cellulare, numero di fax (se presente) e altri dettagli di contatto consentiti dalle leggi applicabili.<\/li>\n<li><strong>Dati di pagamento<\/strong>: Come lo strumento di pagamento (carta di credito, carta di debito) se applicabile, numero di passaporto quando richiesto per ragioni fiscali o di antiriciclaggio.<\/li>\n<li><strong>Informazioni relative alle vendite<\/strong>: Come data, prodotti o servizi forniti, luogo di acquisto, codici dei prodotti, importo, totale delle vendite, numero di partita IVA, reclami, resi, rimborsi e altre informazioni relative alle vendite consentite dalle leggi applicabili.<\/li>\n<li><strong>Abitudini e profili<\/strong>: Come dati relativi ai tuoi acquisti (storia degli acquisti inclusa la boutique in cui avviene la vendita, tipo, quantit\u00e0 e prezzo dei prodotti acquistati), informazioni relative ad attivit\u00e0 e iniziative di gestione della relazione con i clienti (data e categorie di azioni eseguite o da eseguire e risultati delle azioni), abitudini e preferenze di acquisto (lista dei desideri, categorie di prodotti preferite, colore, stile, altri marchi acquistati, paesi pi\u00f9 visitati, come conosci i nostri marchi, taglie, note riguardo alle abitudini di acquisto o necessit\u00e0 speciali dichiarate da te &#8211; ad esempio, materiali preferiti), altre informazioni (informazioni sul lavoro, istruzione, hobby e attivit\u00e0 di stile di vita) consentite dalle leggi applicabili.<\/li>\n<li><strong>Informazioni relative alla famiglia<\/strong>: Come stato civile, data di anniversario, numero di figli, informazioni relative ai figli e altre informazioni relative alla famiglia consentite dalle leggi applicabili.<\/li>\n<\/ul>\n<p><strong>3. COME UTILIZZIAMO I DATI PERSONALI<\/strong><br \/>\nI dati personali possono essere utilizzati per i seguenti scopi, a seconda delle specifiche circostanze in cui interagisci con noi.<\/p>\n<p><strong>3.1 Per le vendite online e in-store<\/strong><br \/>\nI dati personali forniti da te o raccolti quando effettui un acquisto, sia come ospite che come utente registrato, come dettagli personali di base, dettagli di contatto, dati relativi ai tuoi acquisti, dati fiscali, dettagli di pagamento, informazioni relative alle vendite e qualsiasi altro dato strettamente necessario per la consegna dei prodotti, saranno utilizzati:<\/p>\n<ul>\n<li>Per gestire, amministrare ed elaborare il tuo acquisto dei nostri prodotti, vendite e servizi post-vendita, come attivit\u00e0 amministrative, contabili, resi, garanzie, rimborsi tax-free se applicabili, prevenzione delle frodi e comunicazione con te, anche via email, per qualsiasi problema relativo all&#8217;elaborazione degli ordini o a richieste successive riguardanti l&#8217;ordine.<\/li>\n<li>Per rispettare le obbligazioni imposte dalle leggi, regolamenti o legislazione dell&#8217;UE (incluso le leggi antiriciclaggio) e per stabilire o difendere un reclamo legale.<\/li>\n<\/ul>\n<p>Fornire i tuoi dati personali per le finalit\u00e0 sopra indicate \u00e8 necessario; il mancato conferimento renderebbe impossibile completare il tuo acquisto. Salvo diversamente richiesto per conformarsi alle leggi locali applicabili, i dati possono essere trattati per queste finalit\u00e0 senza richiedere il tuo consenso poich\u00e9 \u00e8 necessario per adempiere a obblighi contrattuali e legali.<\/p>\n<p><strong>3.2 Per scopi specifici per cui sono stati forniti<\/strong><br \/>\nI tuoi dati personali forniti da te o raccolti quando richiedi un servizio specifico (ad esempio, registrazione del tuo account sui nostri Siti Web, gestione dei reclami, richiesta di informazioni) saranno utilizzati:<\/p>\n<ul>\n<li>Per fornire i servizi che hai richiesto (ad esempio, operare i processi di registrazione del tuo account, gestire l&#8217;autenticazione sul Sito Web, operare i tuoi account, assisterti, gestire i reclami, gestire le liste dei desideri, seguire qualsiasi domanda o richiesta di contatto che potresti presentarci, anche tramite il nostro servizio clienti).<\/li>\n<li>Per gestire le iscrizioni alle newsletter se non sei anche registrato con noi.<\/li>\n<\/ul>\n<p>Fornire i tuoi dati personali per le finalit\u00e0 sopra indicate \u00e8 necessario; il mancato conferimento renderebbe impossibile soddisfare la tua richiesta. Salvo diversamente richiesto per conformarsi alle leggi locali applicabili, i dati possono essere trattati per queste finalit\u00e0 senza richiedere il tuo consenso poich\u00e9 \u00e8 necessario per dare seguito alla tua richiesta.<\/p>\n<p><strong>3.3 Per scopi di CRM se ti registri con noi<\/strong><br \/>\nI tuoi dati personali forniti da te compilando i nostri moduli o raccolti quando visiti le nostre Boutique, Punti Vendita o Siti Web e interagisci con noi saranno inseriti nel nostro CRM centralizzato per:<\/p>\n<ul>\n<li>Fornirti promozioni, sconti e altri servizi personalizzati, e inviarti newsletter, altre comunicazioni di marketing e commerciali su prodotti, servizi e inviti a eventi relativi ai nostri marchi (organizzati da noi o dalla nostra catena di distribuzione), sondaggi e ricerche, analisi di mercato, inviti a concorsi, lotterie o promozioni e altre iniziative per clienti registrati o contatti dei nostri marchi (&#8220;marketing&#8221;). Possiamo utilizzare metodi di contatto tradizionali (posta, telefono) e\/o digitali e automatizzati (email, SMS, MMS, telefono e altri canali digitali, ad esempio social media) e possiamo inviarti queste comunicazioni in base al tuo profilo, se hai acconsentito alla nostra profilazione.<\/li>\n<li>Analizzare i tuoi contatti con noi, interessi, preferenze e abitudini di acquisto, e creare profili individuali o aggregati basati su queste informazioni per offrirti un servizio migliore, inclusa un&#8217;esperienza di vendita personalizzata in qualsiasi e ogni Boutique e Punto Vendita in Repubblica di San Marino e all&#8217;estero (&#8220;profilazione&#8221;). Possiamo anche utilizzare i dati personali per creare cluster e condurre analisi di mercato e statistiche mirate a identificare prodotti e\/o servizi di interesse per i clienti dei nostri marchi e migliorare i nostri servizi (inclusi i Siti Web). Combineremo i tuoi dati raccolti sui Siti Web con le informazioni che potremmo aver ottenuto attraverso la tua interazione con il personale di vendita presso le Boutique e\/o i Punti Vendita. Il trattamento dei dati personali per la profilazione \u00e8 effettuato in conformit\u00e0 con le garanzie e le misure previste dalla legge applicabile.<\/li>\n<\/ul>\n<p><strong>4. COME CONDIVIDIAMO I DATI PERSONALI<\/strong><\/p>\n<p><strong>4.1 Comunicazione dei dati personali ai responsabili del trattamento<\/strong><br \/>\nQuando acquisti prodotti o utilizzi i nostri servizi di vendita online, i tuoi dati personali possono essere condivisi dal fornitore di e-commerce di questo sito web con terze parti selezionate che forniscono servizi al fornitore, inclusi coloro che elaborano gli ordini, spediscono i prodotti, elaborano i pagamenti con carta di credito o debito e effettuano controlli di prevenzione delle frodi.<\/p>\n<p>I tuoi dati personali possono anche essere condivisi con terze parti, incluse piattaforme digitali (come Meta, Google e altri fornitori menzionati al punto 11 di seguito) per monitorare e analizzare le attivit\u00e0 del sito web e\/o consentire la misurazione delle campagne di marketing, per conto della societ\u00e0 in qualit\u00e0 di responsabili del trattamento dei dati o (come titolari autonomi del trattamento dei dati o contitolari del trattamento) per fornire servizi correlati alle campagne di marketing basate su attivit\u00e0 di tracciamento degli utenti (ad esempio, retargeting). Per capire come queste societ\u00e0 trattano i tuoi dati personali e, se applicabile, modificare le impostazioni di protezione, puoi consultare la sezione privacy su ciascuna piattaforma digitale elencata nella Politica sui Cookie.<\/p>\n<p>I tuoi dati personali possono anche essere condivisi con terze parti per ospitare i contenuti del sito web, fornire servizi tecnici e organizzativi funzionali agli scopi sopra menzionati, conservare i dettagli bancari dei clienti, assistere nell&#8217;invio o nella gestione delle attivit\u00e0 di marketing (oltre a quanto sopra), e gestire email, analisi di mercato, sondaggi, concorsi, programmi di premi o promozioni. Queste terze parti possono avere accesso ai tuoi dati personali, conservarli o trattarli per fornire questi servizi come responsabili del trattamento dei dati per conto della societ\u00e0 in Repubblica di San Marino, nel paese in cui ti trovi, o all&#8217;estero. I fornitori di servizi non sono autorizzati a utilizzare i dati personali per scopi diversi dalla fornitura dei servizi contrattati.<\/p>\n<p>Il trattamento dei tuoi dati personali per scopi di CRM sar\u00e0 effettuato, in conformit\u00e0 con le istruzioni fornite dalla societ\u00e0, dalle imprese associate che gestiscono i marchi della societ\u00e0 a livello locale in Repubblica di San Marino e in altri paesi o online e dai partner commerciali della societ\u00e0 (affiliati e distributori) che gestiscono punti vendita e vendite online sui loro siti web, in qualit\u00e0 di responsabili del trattamento dei dati.<\/p>\n<p><strong>4.2 Divulgazione dei dati personali<\/strong><br \/>\nI tuoi dati personali possono essere condivisi con societ\u00e0 coinvolte nella gestione dei pagamenti e nei controlli di prevenzione delle frodi, che operano in modo indipendente come titolari del trattamento dei dati, per fornirti servizi di vendita online.<\/p>\n<p>In caso di transazioni di capitale o societarie (ad esempio, fusioni o acquisizioni, ristrutturazione aziendale o liquidazione), i dati dei clienti saranno probabilmente uno degli asset trasferiti e possono essere condivisi con i successori legali nella misura consentita dalla legge sulla base dell&#8217;interesse legittimo della societ\u00e0. I dati personali rimarranno soggetti all&#8217;informativa sulla privacy esistente a meno che tu non decida diversamente.<\/p>\n<p>La societ\u00e0 pu\u00f2 anche divulgare i tuoi dati personali a terzi (i) dove previsto da una normativa dell&#8217;UE o di uno Stato membro; (ii) in caso di procedimenti legali; (iii) in risposta a una richiesta da parte delle forze dell&#8217;ordine su basi legittime; o (iv) per proteggere i diritti, la privacy, la sicurezza o la propriet\u00e0 della societ\u00e0 o del pubblico.<\/p>\n<p>Inoltre, nella misura consentita dalla legge, la societ\u00e0 pu\u00f2 divulgare dati personali a terzi in caso di divulgazioni relative all&#8217;uso del sito web, dove ritenuto necessario per investigare, prevenire o intraprendere azioni riguardo ad attivit\u00e0 illecite, sospette frodi o se la societ\u00e0, a sua esclusiva discrezione, ritiene che l&#8217;uso del sito web da parte dell&#8217;utente sia incompatibile con le condizioni effettive del sito web.<\/p>\n<p>L&#8217;elenco completo dei responsabili del trattamento dei dati designati e delle terze parti a cui i dati sono divulgati pu\u00f2 essere ottenuto tramite i nostri contatti elencati di seguito (punto 13).<\/p>\n<p><strong>5. PRIVACY DEI BAMBINI<\/strong><br \/>\nQuesto Sito Web \u00e8 un sito per un pubblico generico; tuttavia, i nostri servizi sono destinati a persone di et\u00e0 pari o superiore a 18 anni. Non richiediamo, raccogliamo, utilizziamo o divulghiamo consapevolmente dati personali forniti da chiunque abbia meno di 18 anni, sia online che nelle Boutique\/Punti Vendita. Se veniamo a conoscenza di aver raccolto dati personali da un bambino, elimineremo tali informazioni. Se hai meno di questa et\u00e0, ti preghiamo di non registrarti o procedere con l&#8217;acquisto online e di chiedere a un adulto (cio\u00e8 i tuoi genitori o il tuo tutore legale) di procedere con le procedure richieste.<\/p>\n<p><strong>6. CONSERVAZIONE, ACCESSIBILIT\u00c0 E TRASFERIMENTO DEI DATI PERSONALI<\/strong><br \/>\nI dati personali raccolti tramite i Siti Web sono principalmente trattati utilizzando mezzi elettronici o web, inclusi i servizi di analisi web ospitati dai server dei nostri fornitori selezionati sia nell&#8217;Unione Europea (ad esempio, Germania e Irlanda, per le transazioni di vendita online sui nostri Siti Web gestiti direttamente) che fuori dall&#8217;Unione Europea (ad esempio, USA, per i nostri servizi di iscrizione alla newsletter). Nelle Boutique e nei Punti Vendita, i dati personali possono essere trattati anche in formato cartaceo. In entrambi i casi, i dati personali saranno inseriti nel nostro database centralizzato e sicuro conservato nella Repubblica di San Marino e gestito dai nostri Customer Relationship Manager e dal team di marketing nella Repubblica di San Marino e all&#8217;estero.<\/p>\n<p>I dati personali saranno accessibili, in base alla necessit\u00e0 e sotto strumenti di controllo di accesso a pi\u00f9 livelli, solo dal personale autorizzato delle nostre Boutique, Punti Vendita e fornitori locali di e-commerce (ad esempio, personale nei dipartimenti digital &amp; IT, marketing, retail, amministrazione e sicurezza). Questo personale \u00e8 tenuto a rispettare gli obblighi di riservatezza ed espressamente designato come incaricato del trattamento, come richiesto dalla legge applicabile. In particolare, se hai acconsentito al trattamento dei tuoi dati personali per scopi di CRM, i dati correlati possono essere letti, modificati e aggiornati dal nostro personale e dal personale presso le Boutique, Punti Vendita e\/o fornitori locali di e-commerce (in particolare il personale di vendita e marketing). Il personale \u00e8 basato nella Repubblica di San Marino o all&#8217;estero ed \u00e8 formato e vincolato da obblighi di riservatezza. Possiamo utilizzarli per raccogliere, utilizzare e divulgare i dati come da noi istruito.<\/p>\n<p>Se dobbiamo trasferire dati personali all&#8217;estero per raggiungere le finalit\u00e0 di questa Informativa sulla Privacy, incluso dove la legislazione sulla protezione dei dati differisce da quella applicabile nel tuo paese, prendiamo misure per garantire che queste comunicazioni avvengano in conformit\u00e0 con gli standard europei di protezione dei dati o altri standard locali nel paese in cui raccogliamo i dati, in modo che i tuoi dati rimangano sicuri e riservati.<\/p>\n<p><strong>7. SICUREZZA E RISERVATEZZA DEI DATI PERSONALI<\/strong><br \/>\nAbbiamo implementato misure appropriate progettate per proteggere i tuoi dati personali dalla perdita accidentale e dall&#8217;accesso, uso, alterazione e divulgazione non autorizzati. Ad esempio, quando fornisci qualsiasi informazione di ordine, utilizziamo la tecnologia Secure Socket Layer (SSL), uno strumento di crittografia che fornisce sicurezza durante la trasmissione di queste informazioni su Internet. Usiamo anche tecnologia firewall, controlli delle password e altre salvaguardie tecnologiche e procedurali per mantenere questo Sito Web. Sebbene abbiamo implementato le misure di sicurezza di cui sopra per questo Sito Web, dovresti essere consapevole che la sicurezza al 100% non \u00e8 possibile. Pertanto, fornire i tuoi dati personali \u00e8 fatto a tuo rischio e, nella massima misura consentita dalla legge applicabile, non avremo alcuna responsabilit\u00e0 come risultato della divulgazione delle tue informazioni personali a causa di errori, omissioni o atti non autorizzati di terzi durante o dopo la loro trasmissione a noi. Ti consigliamo di (i) aggiornare periodicamente il tuo software per proteggere la trasmissione dei dati su reti (ad esempio, software antivirus) e verificare che il tuo fornitore di servizi di comunicazione elettronica abbia adottato mezzi adeguati per la sicurezza della trasmissione dei dati su reti (ad esempio, firewall e filtri anti-spam); (ii) mantenere riservato e non divulgare a nessun altro il tuo nome utente e password per accedere al tuo account; e (iii) cambiare la tua password di tanto in tanto.<\/p>\n<p>Nel caso improbabile in cui ritenessimo che la sicurezza delle tue informazioni personali in nostro possesso o controllo sia stata o possa essere compromessa, ti informeremo di tale sviluppo come richiesto dalla legge applicabile utilizzando uno qualsiasi dei metodi prescritti in tal senso (fornendoci il tuo indirizzo email, acconsenti a ricevere tale notifica in forma elettronica attraverso tale indirizzo email).<\/p>\n<p><strong>8. DIRITTI RELATIVI AI DATI PERSONALI &#8211; GESTIONE DELLE TUE SCELTE<\/strong><\/p>\n<p><strong>8.1 I tuoi diritti<\/strong><br \/>\nIn qualsiasi momento e gratuitamente, puoi accedere ai tuoi dati, ricevere i tuoi dati personali elettronici in un formato strutturato, comunemente usato e leggibile da macchina e trasmetterli a un altro titolare del trattamento (portabilit\u00e0 dei dati), fare correggere, aggiornare, modificare o rimuovere i tuoi dati (fatte salve le eccezioni che possono applicarsi). Puoi aggiornare qualsiasi informazione che ci hai fornito contattandoci agli indirizzi forniti di seguito. Le richieste di eliminazione dei tuoi dati sono soggette a eventuali obblighi legali e di conservazione dei documenti a noi imposti.<\/p>\n<p>Se ritieni che ci sia un problema su come stiamo gestendo i dati personali, hai il diritto di presentare un reclamo alla tua autorit\u00e0 nazionale per la protezione dei dati e\/o a qualsiasi altra autorit\u00e0 di protezione dei dati nell&#8217;UE o nello Spazio Economico Europeo.<\/p>\n<p>Per esercitare questi diritti, puoi inviare la tua richiesta via email a support@mercurifashion.com o tramite posta ordinaria all&#8217;indirizzo elencato di seguito (punto 13). Quando ci contatti, assicurati di fornirci il tuo nome, indirizzo email, indirizzo postale e\/o numero(i) di telefono per assicurarti che gestiamo correttamente la tua richiesta.<\/p>\n<p><strong>8.2 Precisione &#8211; Mantieni i Dati Personali Aggiornati<\/strong><br \/>\nPer aiutarci a servirti meglio, ti invitiamo a rivedere e aggiornare regolarmente i tuoi dati personali. Se sei un utente registrato, puoi accedere e modificare i tuoi dati personali tramite le impostazioni del tuo account utente sul Sito Web; in caso contrario, puoi contattarci (vedi punto 13) per aiutarti ad aggiornare i tuoi dati personali.<\/p>\n<p><strong>8.3 Gestione delle tue scelte in relazione al marketing diretto e alla profilazione<\/strong><br \/>\nSe desideri rinunciare a uno degli scopi di CRM, marketing e\/o profilazione, o gestire le tue preferenze pubblicitarie, puoi semplicemente inviare la tua richiesta a noi (vedi punto 13) o gestire le tue scelte di conseguenza. La stessa procedura si applica se desideri revocare il tuo consenso alla profilazione.<\/p>\n<p><strong>9. DIRITTI DI PRIVACY DELLA CALIFORNIA<\/strong><br \/>\nSe sei un residente della California, puoi richiedere informazioni sulla nostra divulgazione di informazioni personali a terze parti o societ\u00e0 affiliate per i loro scopi di marketing diretto. Per fare tale richiesta, ti preghiamo di inviare una richiesta scritta a noi. Devi inserire la dichiarazione &#8220;Your California Privacy Rights&#8221; nel campo dell&#8217;oggetto. Non siamo responsabili per le notifiche che non sono etichettate o inviate correttamente, o non hanno informazioni complete. Ti preghiamo di consentire 30 giorni per una risposta. Le terze parti non affiliate sono indipendenti da noi, e se desideri ricevere informazioni sulle tue opzioni di divulgazione o interrompere le comunicazioni da tali terze parti, dovrai contattare direttamente tali terze parti non affiliate.<\/p>\n<p><strong>10. CONSERVAZIONE DEI DATI<\/strong><br \/>\nI dati personali saranno conservati per la durata del rapporto commerciale e per tutto il tempo necessario per le finalit\u00e0 descritte in questa Informativa sulla Privacy (ad esempio, se ti iscrivi a una newsletter, per la durata della tua iscrizione; se hai un account utente, fino a quando non chiudi l&#8217;account). Oltre questo periodo, i tuoi dati personali saranno conservati solo per conformarsi ai nostri obblighi legali e normativi (ad esempio, per 10 anni per scopi contabili; per la durata dei requisiti di conservazione obbligatoria per scopi fiscali, ecc.), o per permetterci di mantenere prove dei nostri rispettivi diritti e doveri.<\/p>\n<p>I tuoi dati personali trattati per scopi di CRM (punti 3.3) saranno conservati fino a quando non chiuderai il tuo account o revocherai il tuo consenso al trattamento dei tuoi dati personali per questi scopi. I dati personali relativi ai dettagli dei tuoi acquisti trattati per scopi di profilazione e marketing saranno conservati per un periodo limitato in linea con i tempi consentiti dalla legge applicabile; alla scadenza di questo limite di tempo, i dati personali saranno eliminati o resi anonimi in modo permanente.<\/p>\n<p><strong>11. COOKIE E STRUMENTI DI TRACCIAMENTO ONLINE<\/strong><br \/>\nUtilizziamo strumenti di tracciamento che utilizzano identificatori unici sul Sito Web per raccogliere e salvare informazioni (ad esempio, attraverso l&#8217;uso di cookie, piccoli file di testo memorizzati nel browser del dispositivo utilizzato per visitare il Sito Web) o utilizzare risorse (ad esempio, eseguendo uno script) sul tuo dispositivo quando interagisci con questo Sito Web.<\/p>\n<p>Se hai dato il tuo consenso all&#8217;uso degli strumenti di tracciamento sul Sito Web, impostando le tue preferenze tramite banner o nell&#8217;area preferenze Cookie, possiamo anche utilizzare dati personali, come l&#8217;indirizzo email o postale o il numero di telefono fornito da te, per migliorare, ad esempio, la misurazione delle conversioni effettive dei nostri potenziali clienti sui siti web, attraverso il monitoraggio delle nostre campagne di marketing, nonch\u00e9 per mostrarti annunci pubblicitari e contenuti di marketing coerenti con i tuoi interessi, basati su preferenze e comportamenti dei consumatori identificati attraverso cookie e\/o altri strumenti di tracciamento degli operatori di piattaforme media, inclusi Meta Platforms Ireland Ltd., Google Ireland Limited e altri operatori, seguendo le analisi che effettuano sui loro utenti in base alle loro interazioni. Per ulteriori informazioni sui cookie e gli strumenti di tracciamento che utilizziamo, nonch\u00e9 per scoprire come abilitarli o disabilitarli, consulta la Politica sui Cookie.<\/p>\n<p><strong>12. LINK, INSERZIONISTI, SPONSOR E ANNUNCI PUBBLICITARI<\/strong><br \/>\nQuesto Sito Web pu\u00f2 contenere link ai nostri vari siti web di propriet\u00e0 o controllati, nonch\u00e9 link a siti web di terze parti. Se scegli di fornire i tuoi dati personali su tali siti web collegati, tali informazioni saranno soggette alla politica sulla privacy e alle pratiche di sicurezza di tali siti web collegati &#8211; inclusi i Siti Web gestiti e amministrati dai nostri distributori approvati, ad eccezione dei dati raccolti in essi dai nostri distributori per scopi di CRM ove sia pubblicata la nostra politica sulla privacy &#8211; e non \u00e8 regolata da questa Informativa sulla Privacy. Dovresti familiarizzare con queste altre politiche sulla privacy, poich\u00e9 non siamo responsabili e non abbiamo alcun controllo sulle informazioni inviate a, o raccolte, utilizzate, divulgate o altrimenti trattate da siti web di terze parti.<\/p>\n<p><strong>13. TITOLARE DEL TRATTAMENTO &#8211; COME CONTATTARCI<\/strong><br \/>\nAi fini di questa Informativa sulla Privacy e del trattamento dei dati descritto nella stessa, si prega di notare che &#8220;Noi&#8221;, &#8220;nostro&#8221;, &#8220;ci&#8221; e &#8220;Societ\u00e0&#8221; si riferiscono a MERCURI S.R.L., con sede legale in Via Tre Settembre, 174, 47891 Dogana, Repubblica di San Marino. In qualit\u00e0 di societ\u00e0 holding e proprietaria ultima di diversi marchi attraverso le sue affiliate, inclusa &#8220;MERCURI&#8221;, la Societ\u00e0 \u00e8 il titolare del trattamento dei dati (come definito dal Reg.(UE) 2016\/679) dei dati raccolti nelle Boutique, Punti Vendita e\/o sui Siti Web nella Repubblica di San Marino e all&#8217;estero per scopi di CRM ai sensi dei punti 3.2 e 3.3.<\/p>\n<p><strong>14. AGGIORNAMENTO DI QUESTA POLITICA &#8211; AVVISI<\/strong><br \/>\nCi riserviamo il diritto, a nostra discrezione, di cambiare, modificare, aggiungere o rimuovere parti di questa Informativa sulla Privacy in qualsiasi momento pubblicando tale Informativa sulla Privacy rivista su questa pagina del Sito Web e aggiornando la data di &#8220;Ultima Modifica&#8221; qui sotto. \u00c8 tua responsabilit\u00e0 rivedere di tanto in tanto questa Informativa sulla Privacy per prendere nota di eventuali modifiche apportate. In alcuni casi, potremmo fornire una notifica aggiuntiva delle modifiche materiali a questa Informativa sulla Privacy aggiungendo una dichiarazione sulla homepage di questo Sito Web o, per gli utenti registrati, inviando una email di notifica o aggiungendo una dichiarazione sulla loro pagina account. Accettando tale Informativa sulla Privacy rivista tramite un &#8220;click accetta&#8221; in tale email di notifica o dichiarazione sulla pagina account (resa disponibile quando richiesto per conformarsi alle leggi applicabili), o completando un acquisto sul Sito Web o in qualsiasi negozio dopo che questa Informativa sulla Privacy \u00e8 stata rivista, o, altrimenti, utilizzando o inviando informazioni al Sito Web dopo la pubblicazione dell&#8217;Informativa sulla Privacy rivista, accetti tale Informativa sulla Privacy rivista. Come conseguenza delle modifiche, non verr\u00e0 effettuato alcun trattamento dei tuoi dati senza il tuo esplicito consenso se richiesto dalla legge applicabile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informativa sulla Privacy Informativa sulla Privacy di MERCURI S.R.L. per il sito web mercurifashion.com Questa informativa sulla privacy (di seguito<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-21384","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/mercurifashion.com\/it\/wp-json\/wp\/v2\/pages\/21384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mercurifashion.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mercurifashion.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mercurifashion.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mercurifashion.com\/it\/wp-json\/wp\/v2\/comments?post=21384"}],"version-history":[{"count":1,"href":"https:\/\/mercurifashion.com\/it\/wp-json\/wp\/v2\/pages\/21384\/revisions"}],"predecessor-version":[{"id":21385,"href":"https:\/\/mercurifashion.com\/it\/wp-json\/wp\/v2\/pages\/21384\/revisions\/21385"}],"wp:attachment":[{"href":"https:\/\/mercurifashion.com\/it\/wp-json\/wp\/v2\/media?parent=21384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}